{"id":811,"date":"2022-06-02T20:23:31","date_gmt":"2022-06-02T23:23:31","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=811"},"modified":"2022-06-02T20:23:31","modified_gmt":"2022-06-02T23:23:31","slug":"aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/","title":{"rendered":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial"},"content":{"rendered":"<p>Aruj\u00e1 est\u00e1 prestes a completar 170 anos de funda\u00e7\u00e3o e, para comemorar, haver\u00e1 duas semanas de festa. O in\u00edcio ocorre no dia 08 com o Ato C\u00edvico, na Pra\u00e7a Benedito Ferreira Franco, a famosa Pra\u00e7a do Coreto onde, \u00e0s 9 horas, ocorrer\u00e1 no local o hasteamento das bandeiras. Ainda no dia 08, anivers\u00e1rio da cidade, o prefeito Dr Camargo abre a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto \u00e0s 18h e, \u00e0s 18h30, ir\u00e1 abrir o Portal da festa no Centro Residencial (perto da Sorveteria Natureza), que contar\u00e1 com shows de grandes artistas nacionais e locais. Na Pra\u00e7a do Coreto haver\u00e1 uma s\u00e9rie de shows do dia 08 ao dia 19 (vide programa\u00e7\u00e3o). No local, tamb\u00e9m haver\u00e1 barracas de comes e bebes de comidas t\u00edpicas de v\u00e1rias nacionalidades, bem como atra\u00e7\u00f5es de lazer e entretenimento para a popula\u00e7\u00e3o.<br \/>\nAinda no dia 08, primeiro dia da Festa no Centro Residencial, haver\u00e1 o show de abertura do cantor Luan Santana e dos artistas locais Aline &amp; S\u00e9rgio e Banda e tamb\u00e9m Silvana Cardoso &amp; Banda, durante \u00e0 noite. Tamb\u00e9m haver\u00e1 comes e bebes, tirolesa e parque de divers\u00e3o. A entrada \u00e9 gratuita e quem quiser colaborar com 1kg de alimento n\u00e3o perec\u00edvel pode procurar as equipes e a barraca do Fundo Social de Solidariedade de Aruj\u00e1. A programa\u00e7\u00e3o da festa no Centro Residencial vai do dia 08 ao dia 12 de junho e, al\u00e9m do cantor Luan Santana, haver\u00e1 shows de outros cantores nacionais e locais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aruj\u00e1 est\u00e1 prestes a completar 170 anos de funda\u00e7\u00e3o e, para comemorar, haver\u00e1 duas semanas de festa. O in\u00edcio ocorre no dia 08 com o Ato C\u00edvico, na Pra\u00e7a Benedito Ferreira Franco, a famosa Pra\u00e7a do Coreto onde, \u00e0s 9 horas, ocorrer\u00e1 no local o hasteamento das bandeiras. Ainda no dia 08, anivers\u00e1rio da cidade, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-811","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aruja"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Aruj\u00e1 est\u00e1 prestes a completar 170 anos de funda\u00e7\u00e3o e, para comemorar, haver\u00e1 duas semanas de festa. O in\u00edcio ocorre no dia 08 com o Ato C\u00edvico, na Pra\u00e7a Benedito Ferreira Franco, a famosa Pra\u00e7a do Coreto onde, \u00e0s 9 horas, ocorrer\u00e1 no local o hasteamento das bandeiras. Ainda no dia 08, anivers\u00e1rio da cidade, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T23:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial\",\"datePublished\":\"2022-06-02T23:23:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg\",\"articleSection\":[\"Aruj\u00e1\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/\",\"name\":\"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg\",\"datePublished\":\"2022-06-02T23:23:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/","og_locale":"pt_BR","og_type":"article","og_title":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole","og_description":"Aruj\u00e1 est\u00e1 prestes a completar 170 anos de funda\u00e7\u00e3o e, para comemorar, haver\u00e1 duas semanas de festa. O in\u00edcio ocorre no dia 08 com o Ato C\u00edvico, na Pra\u00e7a Benedito Ferreira Franco, a famosa Pra\u00e7a do Coreto onde, \u00e0s 9 horas, ocorrer\u00e1 no local o hasteamento das bandeiras. Ainda no dia 08, anivers\u00e1rio da cidade, [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-06-02T23:23:31+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial","datePublished":"2022-06-02T23:23:31+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg","articleSection":["Aruj\u00e1"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/","url":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/","name":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg","datePublished":"2022-06-02T23:23:31+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/06\/WhatsApp-Image-2022-06-02-at-20.12.50.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/aniversario-de-aruja-sera-comemorado-em-grande-estilo-com-a-festa-das-nacoes-na-praca-do-coreto-e-varios-shows-no-centro-residencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Anivers\u00e1rio de Aruj\u00e1 ser\u00e1 comemorado em grande estilo, com a Festa das Na\u00e7\u00f5es na Pra\u00e7a do Coreto e v\u00e1rios shows no Centro Residencial"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/811\/revisions"}],"predecessor-version":[{"id":813,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/811\/revisions\/813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/812"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}