{"id":2704,"date":"2022-09-04T11:44:35","date_gmt":"2022-09-04T14:44:35","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=2704"},"modified":"2022-09-04T11:47:35","modified_gmt":"2022-09-04T14:47:35","slug":"marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/","title":{"rendered":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio"},"content":{"rendered":"<p>Em Bras\u00edlia, a For\u00e7a tamb\u00e9m desfila na Esplanada dos Minist\u00e9rios<\/p>\n<p>O 7 de Setembro deste ano est\u00e1 repleto de hist\u00f3ria. S\u00e3o 200 anos de Brasil independente de Portugal, mote que est\u00e1 orientando o desfile c\u00edvico-militar na Esplanada dos Minist\u00e9rios, em Bras\u00edlia, na pr\u00f3xima quarta-feira (7), pela manh\u00e3.<\/p>\n<p>A Marinha do Brasil, como tradicionalmente ocorre, \u00e9 uma das For\u00e7as Armadas a participar do desfile. Detalhes foram antecipados pelo contra-almirante Gustavo Calero Garriga Pires, comandante de Opera\u00e7\u00f5es Mar\u00edtimas e Prote\u00e7\u00e3o da Amaz\u00f4nia Azul, o entrevistado deste domingo do programa Brasil em Pauta, da TV Brasil.<\/p>\n<p>O contra-almirante Gustavo Calero Garriga Pires destacou a parada Naval da Marinha, no Rio de Janeiro. \u201cN\u00f3s teremos tamb\u00e9m, neste 7 de Setembro, uma parada naval com nossos navios da esquadra brasileira e de guerra de marinhas amigas, que foram convidadas para a celebra\u00e7\u00e3o. A parada naval vai ocorrer no mesmo dia no litoral da cidade do Rio de Janeiro, come\u00e7ando no in\u00edcio da manh\u00e3, no Recreio dos Bandeirantes, e seguindo por toda a orla at\u00e9 a praia do Leme\u2019\u2019.<\/p>\n<p>Amaz\u00f4nia Azul<br \/>\nAl\u00e9m da participa\u00e7\u00e3o da Marinha nas comemora\u00e7\u00f5es dos 200 anos da Independ\u00eancia do Brasil, o contra-almirante Gustavo Calero Garriga Pires detalhou, durante o Brasil em Pauta, o pleito do Brasil, junto ao Conselho de Limites da Plataforma Continental da ONU, de ampliar a extens\u00e3o da Amaz\u00f4nia Azul.<\/p>\n<p>Rica em recursos naturais e minerais como o petr\u00f3leo do pr\u00e9-sal, a Amaz\u00f4nia Azul assemelha-se a uma &#8220;moldura&#8221; da costa brasileira, em dire\u00e7\u00e3o ao Oceano Atl\u00e2ntico. S\u00f3 que esta \u201cmoldura&#8221; tem atualmente 3,5 milh\u00f5es de quil\u00f4metros quadrados (km\u00b2) e o governo brasileiro quer adicionar mais 2,2 milh\u00f5es de km\u00b2 ao espa\u00e7o marinho, pleito que, se for aceito pelas Na\u00e7\u00f5es Unidas, elevar\u00e1 a jurisdi\u00e7\u00e3o brasileira sobre uma regi\u00e3o mar\u00edtima de 5,7 milh\u00f5es de km\u00b2.<\/p>\n<p>\u201cEstamos falando de dimens\u00f5es que v\u00e3o, normalmente, com algumas exce\u00e7\u00f5ea, a cerca de 400 quil\u00f4metros da costa. Ent\u00e3o, contando a partir da costa, \u00e9 basicamente isso, o espa\u00e7o geogr\u00e1fico em que consideramos, que denominamos Amaz\u00f4nia Azul, cheia de riquezas, cheio de possibilidades. Se a gente contar sob o ponto de vista econ\u00f4mico e de v\u00e1rios outros pontos de vista tamb\u00e9m, \u00e9 de uma riqueza sem igual para o nosso pa\u00eds.\u201d<\/p>\n<p>A amplia\u00e7\u00e3o da Amaz\u00f4nia Azul pode ter impactos econ\u00f4micos para o Brasil que v\u00e3o al\u00e9m dos hidrocarbonetos, no caso, o petr\u00f3leo do pr\u00e9-sal. Segundo a Organiza\u00e7\u00e3o para a Coopera\u00e7\u00e3o e o Desenvolvimento Econ\u00f4mico (OCDE), a atividade econ\u00f4mica no mar vai movimentar US$ 3 trilh\u00f5es e gerar mais de 40 milh\u00f5es de empregos no mundo at\u00e9 2030. Mas a gest\u00e3o dessa \u00e1rea mar\u00edtima tamb\u00e9m traz desafios e amea\u00e7as para a Marinha brasileira, como relatou o contra-almirante Calero Garriga Pires.<\/p>\n<p>\u201cIdentificamos amea\u00e7as cibern\u00e9ticas que podem interferir, por exemplo, no tr\u00e1fego mar\u00edtimo, o pr\u00f3prio terrorismo. Lembrar que n\u00f3s temos infraestruturas cr\u00edticas fundamentais na nossa Amaz\u00f4nia Azul. Acesso ilegal \u00e0 biodiversidade, o meio ambiente \u00e9 uma grande preocupa\u00e7\u00e3o nossa. Ent\u00e3o h\u00e1 efetivamente uma s\u00e9rie de amea\u00e7as, e a Marinha trabalha dia e noite, 24 horas por dia, sete dias por semana, para estar a altura dessas amea\u00e7as e se contrapor a elas\u2019\u2019.<\/p>\n<p>Opera\u00e7\u00f5es<br \/>\nAinda para o Brasil em Pauta, o comandante de Opera\u00e7\u00f5es Mar\u00edtimas e Prote\u00e7\u00e3o da Amaz\u00f4nia Azul, Gustavo Calero Garriga Pires, falou sobre o salvamento e resgate de pessoas e as a\u00e7\u00f5es de interoperabilidade com outras estruturas de seguran\u00e7a na costa do pa\u00eds.<\/p>\n<p>Segundo Calero Garriga Pires, cerca de 300 pessoas j\u00e1 foram resgatadas neste ano em a\u00e7\u00f5es de busca e salvamento na costa brasileira. Opera\u00e7\u00f5es conjuntas tamb\u00e9m est\u00e3o apresentando resultados, como a apreens\u00e3o de drogas efetuada pela Marinha e a Pol\u00edcia Federal, em 19 de agosto, no litoral cearense.<\/p>\n<p>\u02dcNa costa do Cear\u00e1, um navio de guerra da Marinha do Brasil interceptou uma embarca\u00e7\u00e3o de bandeira brasileira que tinha mais de uma tonelada de pasta base de coca\u00edna com agentes da Pol\u00edcia Federal embarcados, ou seja, n\u00f3s desenvolvemos a nossa opera\u00e7\u00e3o em conjunto, neste caso, com a Pol\u00edcia Federal em prol de coibir o tr\u00e1fico internacional de drogas.\u02dc<\/p>\n<p>O Brasil em Pauta com o contra-almirante Gustavo Calero Garriga Pires vai ao ar neste domingo (4), \u00e0s 22h30, aqui na TV Brasil.<\/p>\n<p>*Com informa\u00e7\u00f5es de Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Bras\u00edlia, a For\u00e7a tamb\u00e9m desfila na Esplanada dos Minist\u00e9rios O 7 de Setembro deste ano est\u00e1 repleto de hist\u00f3ria. S\u00e3o 200 anos de Brasil independente de Portugal, mote que est\u00e1 orientando o desfile c\u00edvico-militar na Esplanada dos Minist\u00e9rios, em Bras\u00edlia, na pr\u00f3xima quarta-feira (7), pela manh\u00e3. A Marinha do Brasil, como tradicionalmente ocorre, \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":{"0":"post-2704","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-geral"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Em Bras\u00edlia, a For\u00e7a tamb\u00e9m desfila na Esplanada dos Minist\u00e9rios O 7 de Setembro deste ano est\u00e1 repleto de hist\u00f3ria. S\u00e3o 200 anos de Brasil independente de Portugal, mote que est\u00e1 orientando o desfile c\u00edvico-militar na Esplanada dos Minist\u00e9rios, em Bras\u00edlia, na pr\u00f3xima quarta-feira (7), pela manh\u00e3. A Marinha do Brasil, como tradicionalmente ocorre, \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-04T14:44:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-04T14:47:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"645\" \/>\n\t<meta property=\"og:image:height\" content=\"398\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Marinha participa do 7 de Setembro com parada naval no litoral do Rio\",\"datePublished\":\"2022-09-04T14:44:35+00:00\",\"dateModified\":\"2022-09-04T14:47:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/\"},\"wordCount\":787,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/\",\"name\":\"Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg\",\"datePublished\":\"2022-09-04T14:44:35+00:00\",\"dateModified\":\"2022-09-04T14:47:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg\",\"width\":645,\"height\":398,\"caption\":\"Foto: T\u00e2nia R\u00eago\\\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marinha participa do 7 de Setembro com parada naval no litoral do Rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/","og_locale":"pt_BR","og_type":"article","og_title":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole","og_description":"Em Bras\u00edlia, a For\u00e7a tamb\u00e9m desfila na Esplanada dos Minist\u00e9rios O 7 de Setembro deste ano est\u00e1 repleto de hist\u00f3ria. S\u00e3o 200 anos de Brasil independente de Portugal, mote que est\u00e1 orientando o desfile c\u00edvico-militar na Esplanada dos Minist\u00e9rios, em Bras\u00edlia, na pr\u00f3xima quarta-feira (7), pela manh\u00e3. A Marinha do Brasil, como tradicionalmente ocorre, \u00e9 [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-09-04T14:44:35+00:00","article_modified_time":"2022-09-04T14:47:35+00:00","og_image":[{"width":645,"height":398,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio","datePublished":"2022-09-04T14:44:35+00:00","dateModified":"2022-09-04T14:47:35+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/"},"wordCount":787,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/","url":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/","name":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg","datePublished":"2022-09-04T14:44:35+00:00","dateModified":"2022-09-04T14:47:35+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-04-at-10.12.38-1.jpeg","width":645,"height":398,"caption":"Foto: T\u00e2nia R\u00eago\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/marinha-participa-do-7-de-setembro-com-parada-naval-no-litoral-do-rio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Marinha participa do 7 de Setembro com parada naval no litoral do Rio"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=2704"}],"version-history":[{"count":3,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2704\/revisions"}],"predecessor-version":[{"id":2709,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2704\/revisions\/2709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/2707"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=2704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}