{"id":2377,"date":"2022-08-22T11:19:38","date_gmt":"2022-08-22T14:19:38","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=2377"},"modified":"2022-08-22T11:20:24","modified_gmt":"2022-08-22T14:20:24","slug":"renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/","title":{"rendered":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0"},"content":{"rendered":"<p>O cantor e compositor Renato Teixeira est\u00e1 entre as atra\u00e7\u00f5es confirmadas nas celebra\u00e7\u00f5es da 281\u00aa Festa de Nossa Senhora de Bonsucesso e sobe ao palco principal no pr\u00f3ximo domingo (28), \u00e0s 19h30. A programa\u00e7\u00e3o cultural realizada pela Prefeitura de Guarulhos, por meio da Secretaria de Cultura, acontece neste fim de semana,\u00a0s\u00e1bado\u00a0(27) e\u00a0domingo, a partir das 8h, e conta com apresenta\u00e7\u00f5es musicais gratuitas no palco principal e no Rancho dos Romeiros.<\/p>\n<p>Gastronomia especial, interven\u00e7\u00f5es art\u00edsticas e artesanato local tamb\u00e9m integram os festejos. No\u00a0s\u00e1bado\u00a0os participantes da 21\u00aa Romaria a Nossa Senhora de Bonsucesso se concentram a partir das 9h em frente \u00e0 Capela Nossa Senhora Aparecida, na rua N-Tr\u00eas, Inocoop, com sa\u00edda prevista para as 10h em clima de louvor e alegria.<\/p>\n<p>Idealizada pelo poeta cordelista Bosco Maciel, a prociss\u00e3o re\u00fane romeiros que ao longo de todo o percurso cantam, dan\u00e7am, recitam poesias e fazem performances teatrais, sempre ao som de m\u00fasicas folcl\u00f3ricas. Nesta edi\u00e7\u00e3o a romaria conta com a participa\u00e7\u00e3o de artistas ligados \u00e0 cultura popular, como Congada Santa Ifig\u00eania, Capoeira Alian\u00e7a Negra,\u00a0Maracatu Terra Forte e\u00a0as folias de reis Estrela Dalva, Mensageiros de Santos Reis e Vila Carmela, entre outros.<\/p>\n<p>Palco principal<br \/>\nAinda no\u00a0s\u00e1bado, a partir das 16h, os espet\u00e1culos oferecidos pela Secretaria de Cultura no palco principal ampliam o conceito cultural da 281\u00aa Festa de Nossa Senhora do Bonsucesso ao trazer para o evento os artistas Let\u00edcia D\u2019Alma, C\u00e9sar Balbino, Luigi Santo, Kleber &amp; Al\u00ea, Karolainy &amp; Leonardo e Vanessa Ajalla.<\/p>\n<p>No\u00a0domingo\u00a0(28) o palco principal exalta a m\u00fasica brasileira com shows do cantor e compositor guarulhense Amauri Falabella, \u00e0s 16h45, e Renato Teixeira, \u00e0s 19h30. Entre as composi\u00e7\u00f5es de Teixeira que ficaram conhecidas pelo grande p\u00fablico est\u00e3o\u00a0Romaria, grande sucesso na voz de Elis Regina,\u00a0Tocando em Frente, parceria com o m\u00fasico Almir Sater e gravada por Maria Beth\u00e2nia,\u00a0Dad\u00e1 Maria, dueto com Gal Costa,\u00a0Frete, tema de abertura do seriado\u00a0Carga Pesada, da Rede Globo, al\u00e9m do grande sucesso\u00a0Amanheceu, Peguei a Viola.<br \/>\nJ\u00e1 Amauri Falabella tem mais de 40 anos de estrada, uma trajet\u00f3ria musical com influ\u00eancias de artistas como Elomar, Xangai, Vidal Fran\u00e7a e D\u00e9rcio Marques. Suas m\u00fasicas reafirmam sua fidelidade com as ra\u00edzes da m\u00fasica brasileira, composi\u00e7\u00f5es sens\u00edveis que primam pela riqueza dos arranjos e um tra\u00e7o em comum que une todas as m\u00fasicas: o respeito \u00e0 natureza e o amor \u00e0 simplicidade.<\/p>\n<p>Rancho dos Romeiros<br \/>\nO Rancho dos Romeiros \u00e9 um espa\u00e7o concebido para acolher os romeiros que chegam de diferentes regi\u00f5es do Estado ao Santu\u00e1rio de Nossa Senhora de Bonsucesso. Ali a viola caipira, as comidas t\u00edpicas e a chegada dos tropeiros celebram uma tradi\u00e7\u00e3o antiga, ligada \u00e0 cultura popular sertaneja, cujo foco \u00e9 a uni\u00e3o de diferentes culturas para perpetuar o uso da viola, do viol\u00e3o e da sanfona.<\/p>\n<p>No\u00a0s\u00e1bado, \u00e0s 13h, o rancho oferece m\u00fasica caipira para encher o cora\u00e7\u00e3o de saudade com apresenta\u00e7\u00e3o de Maria Jos\u00e9 e dos grupos M\u00fasica do Interior, \u00e0s 16h, e Quarteto Raiz, \u00e0s 17h, e dos convidados Di Oriente, Leandro &amp; Vanito, Pires &amp; Claudinei, Tony Sobrinho, Z\u00e9 Ant\u00f4nio &amp; Ana Lucia e Z\u00e9 Moreno &amp; Mulatinho.<\/p>\n<p>J\u00e1 no\u00a0domingo, tamb\u00e9m \u00e0s 13h, quem passar pelo rancho poder\u00e1 conferir as graciosas investidas sonoras da apresentadora Vera Bianca e sua sanfona, acompanhada pelo m\u00fasico Fabinho, pelo show do duo Quando o Inhambu Cantou no Meu Quintal e os convidados Ryan Fernando &amp; Colimar, Zenon &amp; Jo\u00e3o Garcia, Minelle &amp; Jo\u00e3o do Prado, Fabio Reis &amp; Tony Viola, Rafael Viola &amp; Nascimento, Betto Ponciano Violeiro e Ot\u00e1vio Ventura &amp; Thiago Cavalcante.<\/p>\n<p>Para conhecer a programa\u00e7\u00e3o completa da 281\u00aa Festa de Nossa Senhora de Bonsucesso acesse\u00a0https:\/\/www.guarulhos.sp.gov.br\/node\/19482.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cantor e compositor Renato Teixeira est\u00e1 entre as atra\u00e7\u00f5es confirmadas nas celebra\u00e7\u00f5es da 281\u00aa Festa de Nossa Senhora de Bonsucesso e sobe ao palco principal no pr\u00f3ximo domingo (28), \u00e0s 19h30. A programa\u00e7\u00e3o cultural realizada pela Prefeitura de Guarulhos, por meio da Secretaria de Cultura, acontece neste fim de semana,\u00a0s\u00e1bado\u00a0(27) e\u00a0domingo, a partir das [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-2377","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guarulhos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"O cantor e compositor Renato Teixeira est\u00e1 entre as atra\u00e7\u00f5es confirmadas nas celebra\u00e7\u00f5es da 281\u00aa Festa de Nossa Senhora de Bonsucesso e sobe ao palco principal no pr\u00f3ximo domingo (28), \u00e0s 19h30. A programa\u00e7\u00e3o cultural realizada pela Prefeitura de Guarulhos, por meio da Secretaria de Cultura, acontece neste fim de semana,\u00a0s\u00e1bado\u00a0(27) e\u00a0domingo, a partir das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T14:19:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-22T14:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0\",\"datePublished\":\"2022-08-22T14:19:38+00:00\",\"dateModified\":\"2022-08-22T14:20:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/\"},\"wordCount\":674,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg\",\"articleSection\":[\"Guarulhos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/\",\"name\":\"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg\",\"datePublished\":\"2022-08-22T14:19:38+00:00\",\"dateModified\":\"2022-08-22T14:20:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/","og_locale":"pt_BR","og_type":"article","og_title":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole","og_description":"O cantor e compositor Renato Teixeira est\u00e1 entre as atra\u00e7\u00f5es confirmadas nas celebra\u00e7\u00f5es da 281\u00aa Festa de Nossa Senhora de Bonsucesso e sobe ao palco principal no pr\u00f3ximo domingo (28), \u00e0s 19h30. A programa\u00e7\u00e3o cultural realizada pela Prefeitura de Guarulhos, por meio da Secretaria de Cultura, acontece neste fim de semana,\u00a0s\u00e1bado\u00a0(27) e\u00a0domingo, a partir das [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-08-22T14:19:38+00:00","article_modified_time":"2022-08-22T14:20:24+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0","datePublished":"2022-08-22T14:19:38+00:00","dateModified":"2022-08-22T14:20:24+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/"},"wordCount":674,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg","articleSection":["Guarulhos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/","url":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/","name":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0 - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg","datePublished":"2022-08-22T14:19:38+00:00","dateModified":"2022-08-22T14:20:24+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-22-at-10.34.09.jpeg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/renato-teixeira-e-atracao-na-281a-festa-de-nossa-senhora-de-bonsucesso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Renato Teixeira \u00e9 atra\u00e7\u00e3o na 281\u00aa Festa de Nossa Senhora de Bonsucesso \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2377\/revisions"}],"predecessor-version":[{"id":2379,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/2377\/revisions\/2379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/2378"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=2377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=2377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}