{"id":21597,"date":"2024-11-06T10:52:15","date_gmt":"2024-11-06T13:52:15","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=21597"},"modified":"2024-11-06T10:52:15","modified_gmt":"2024-11-06T13:52:15","slug":"comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/","title":{"rendered":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base"},"content":{"rendered":"<p><em>Grupo liderado pelo vice-prefeito eleito, T\u00e9o Cusatis, se re\u00fane com os integrantes da atual gest\u00e3o para restabelecer os prazos e disponibiliza\u00e7\u00e3o dos espa\u00e7os para o trabalho<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Comiss\u00e3o de Transi\u00e7\u00e3o da nova gest\u00e3o eleita para administrar Mogi das Cruzes, a partir de 1\u00ba de janeiro de 2025, se reuniu com o grupo da Prefeitura Municipal encarregado em disponibilizar os dados e os espa\u00e7os solicitados. \u201cFoi uma reuni\u00e3o t\u00e9cnica, agora com os membros da atual gest\u00e3o. Ajustamos os prazos e reafirmamos a necessidade de usarmos a Escola de Gest\u00e3o e Governo como base dos trabalhos e acelerar as informa\u00e7\u00f5es\u201d, destacou o vice-prefeito eleito (2025\/2028), T\u00e9o Cusatis.<\/p>\n<p>Segundo ele, o primeiro prazo apresentado era 1\u00ba de novembro, j\u00e1 com objetivo de receber os primeiros contratos para an\u00e1lise. \u201cMas no decreto publicado pela atual administra\u00e7\u00e3o, essas datas foram alteradas e n\u00f3s precis\u00e1vamos restabelecer o cronograma e reafirmar a necessidade de termos o maior n\u00famero de informa\u00e7\u00f5es poss\u00edveis e obter o extrato real da Prefeitura que iremos assumir no dia 1\u00ba de janeiro\u201d.<\/p>\n<p>Nesta primeira fase, est\u00e3o programados os trabalhos dentro de par\u00e2metros mais t\u00e9cnicos, envolvendo principalmente as \u00e1reas t\u00e9cnicas e jur\u00eddicas da Prefeitura de Mogi das Cruzes. Na sequ\u00eancia, conforme o vice-prefeito eleito, entram as C\u00e2maras T\u00e9cnicas, com o objetivo de obter os dados e um extrato do funcionamento das Secretarias e Coordenadorias, fundamentalmente aquelas que tenham presta\u00e7\u00e3o de servi\u00e7o direto \u00e0 comunidade, como Sa\u00fade, Educa\u00e7\u00e3o, Transportes e a pr\u00f3pria zeladoria da cidade.<\/p>\n<p>\u201c\u00c9 preciso que tenhamos uma continuidade desses servi\u00e7os sem qualquer preju\u00edzo \u00e0 popula\u00e7\u00e3o e uma das nossas maiores preocupa\u00e7\u00f5es diz respeito aos contratos que est\u00e3o vencendo para que n\u00e3o tenhamos descontinuidade dos servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o\u201d, destaca o vice-prefeito eleito, que coordenou a reuni\u00e3o desta ter\u00e7a-feira. Tamb\u00e9m participaram do encontro os seguintes integrantes da comiss\u00e3o formada por parte da prefeita eleita, Mara Bertaiolli. S\u00e3o eles: Filipe Augusto Lima Hermanson Carvalho, Neusa Marialva, Guilherme Luiz Sever, Robson Senziali e Patr\u00edcia Cesare.<\/p>\n<p><strong>ESCOLA DE GOVERNO<\/strong> \u2013 Ap\u00f3s a reuni\u00e3o, foi disponibilizada, conforme solicitado, a Escola de Governo e Gest\u00e3o e o grupo dever\u00e1 dar in\u00edcio aos trabalhos t\u00e9cnicos no local ainda nesta semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grupo liderado pelo vice-prefeito eleito, T\u00e9o Cusatis, se re\u00fane com os integrantes da atual gest\u00e3o para restabelecer os prazos e disponibiliza\u00e7\u00e3o dos espa\u00e7os para o trabalho &nbsp; A Comiss\u00e3o de Transi\u00e7\u00e3o da nova gest\u00e3o eleita para administrar Mogi das Cruzes, a partir de 1\u00ba de janeiro de 2025, se reuniu com o grupo da Prefeitura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-21597","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mogi-das-cruzes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Grupo liderado pelo vice-prefeito eleito, T\u00e9o Cusatis, se re\u00fane com os integrantes da atual gest\u00e3o para restabelecer os prazos e disponibiliza\u00e7\u00e3o dos espa\u00e7os para o trabalho &nbsp; A Comiss\u00e3o de Transi\u00e7\u00e3o da nova gest\u00e3o eleita para administrar Mogi das Cruzes, a partir de 1\u00ba de janeiro de 2025, se reuniu com o grupo da Prefeitura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T13:52:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base\",\"datePublished\":\"2024-11-06T13:52:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg\",\"articleSection\":[\"Mogi das Cruzes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/\",\"name\":\"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg\",\"datePublished\":\"2024-11-06T13:52:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/","og_locale":"pt_BR","og_type":"article","og_title":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole","og_description":"Grupo liderado pelo vice-prefeito eleito, T\u00e9o Cusatis, se re\u00fane com os integrantes da atual gest\u00e3o para restabelecer os prazos e disponibiliza\u00e7\u00e3o dos espa\u00e7os para o trabalho &nbsp; A Comiss\u00e3o de Transi\u00e7\u00e3o da nova gest\u00e3o eleita para administrar Mogi das Cruzes, a partir de 1\u00ba de janeiro de 2025, se reuniu com o grupo da Prefeitura [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2024-11-06T13:52:15+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base","datePublished":"2024-11-06T13:52:15+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg","articleSection":["Mogi das Cruzes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/","url":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/","name":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg","datePublished":"2024-11-06T13:52:15+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-07.13.16.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/comissao-de-transicao-ajusta-datas-e-define-escola-de-governo-como-base\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Comiss\u00e3o de Transi\u00e7\u00e3o ajusta datas e define Escola de Governo como base"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=21597"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21597\/revisions"}],"predecessor-version":[{"id":21599,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21597\/revisions\/21599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/21598"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=21597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=21597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=21597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}