{"id":21231,"date":"2024-10-22T11:31:36","date_gmt":"2024-10-22T14:31:36","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=21231"},"modified":"2024-10-22T11:31:36","modified_gmt":"2024-10-22T14:31:36","slug":"confira-as-selecoes-de-emprego-da-semana-em-itaqua-5","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/","title":{"rendered":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1"},"content":{"rendered":"<p>Vagas s\u00e3o para pessoas com ou sem experi\u00eancia<\/p>\n<p>O programa Itaqu\u00e1 Mais Emprego oferece, neste momento, 1,5 mil oportunidades e as sele\u00e7\u00f5es da semana, sempre \u00e0s 10h, s\u00e3o para os cargos de auxiliar de log\u00edstica e motorista de fretado. Para participar \u00e9 necess\u00e1rio ter a partir de 18 anos.<\/p>\n<p>Nesta ter\u00e7a (22), a sele\u00e7\u00e3o \u00e9 para auxiliar de log\u00edstica com ou sem experi\u00eancia que tenha ensino m\u00e9dio completo. Na quarta (23) ser\u00e1 para motorista de fretado com experi\u00eancia, CNH D e disponibilidade para viajar. J\u00e1 na quinta (24), a sele\u00e7\u00e3o \u00e9 novamente para auxiliar de log\u00edstica com fundamental completo.<\/p>\n<p>\u201cA cada semana novas oportunidades entram em nosso mural de emprego. Temos vagas para diferentes \u00e1reas e perfis. \u00c9 a chance do mun\u00edcipe conseguir sua recoloca\u00e7\u00e3o no mercado\u201d, disse o secret\u00e1rio de Emprego e Desenvolvimento Econ\u00f4mico, Luciano D\u00e1vila.<\/p>\n<p>Para participar \u00e9 necess\u00e1rio comparecer com o RG, CPF, curr\u00edculo impresso e caneta. O atendimento \u00e9 por ordem de chegada e com limite de senha. As entrevistas acontecem na Secretaria de Emprego e Desenvolvimento Econ\u00f4mico (rua Dom Thomaz Frey, 89 \u2013 Centro).<\/p>\n<p>Outras oportunidades podem ser encontradas no mural de vagas (cutt.ly\/gwtFn1hh). \u201c\u00c9 importante o candidato ficar atento ao site e verificar a vaga que mais se encaixa com seu perfil. Vamos encerrar o m\u00eas de outubro preenchendo muitas vagas\u201d, acrescentou o prefeito Eduardo Boigues.<\/p>\n<p>Foto: Dayane Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vagas s\u00e3o para pessoas com ou sem experi\u00eancia O programa Itaqu\u00e1 Mais Emprego oferece, neste momento, 1,5 mil oportunidades e as sele\u00e7\u00f5es da semana, sempre \u00e0s 10h, s\u00e3o para os cargos de auxiliar de log\u00edstica e motorista de fretado. Para participar \u00e9 necess\u00e1rio ter a partir de 18 anos. Nesta ter\u00e7a (22), a sele\u00e7\u00e3o \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-21231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-itaqua"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Vagas s\u00e3o para pessoas com ou sem experi\u00eancia O programa Itaqu\u00e1 Mais Emprego oferece, neste momento, 1,5 mil oportunidades e as sele\u00e7\u00f5es da semana, sempre \u00e0s 10h, s\u00e3o para os cargos de auxiliar de log\u00edstica e motorista de fretado. Para participar \u00e9 necess\u00e1rio ter a partir de 18 anos. Nesta ter\u00e7a (22), a sele\u00e7\u00e3o \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-22T14:31:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1\",\"datePublished\":\"2024-10-22T14:31:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg\",\"articleSection\":[\"Itaqu\u00e1\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/\",\"name\":\"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg\",\"datePublished\":\"2024-10-22T14:31:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole","og_description":"Vagas s\u00e3o para pessoas com ou sem experi\u00eancia O programa Itaqu\u00e1 Mais Emprego oferece, neste momento, 1,5 mil oportunidades e as sele\u00e7\u00f5es da semana, sempre \u00e0s 10h, s\u00e3o para os cargos de auxiliar de log\u00edstica e motorista de fretado. Para participar \u00e9 necess\u00e1rio ter a partir de 18 anos. Nesta ter\u00e7a (22), a sele\u00e7\u00e3o \u00e9 [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2024-10-22T14:31:36+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1","datePublished":"2024-10-22T14:31:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg","articleSection":["Itaqu\u00e1"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/","url":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/","name":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1 - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg","datePublished":"2024-10-22T14:31:36+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/10\/WhatsApp-Image-2024-10-22-at-09.23.26.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/confira-as-selecoes-de-emprego-da-semana-em-itaqua-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Confira as sele\u00e7\u00f5es de emprego da semana em Itaqu\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=21231"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21231\/revisions"}],"predecessor-version":[{"id":21233,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/21231\/revisions\/21233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/21232"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=21231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=21231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=21231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}