{"id":1827,"date":"2022-07-29T08:10:34","date_gmt":"2022-07-29T11:10:34","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=1827"},"modified":"2022-07-29T08:10:34","modified_gmt":"2022-07-29T11:10:34","slug":"procon-pede-que-quata-mude-embalagem-de-soro-de-leite","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/","title":{"rendered":"Procon pede que Quat\u00e1 mude embalagem de soro de leite"},"content":{"rendered":"<p>Apresenta\u00e7\u00e3o do produto pode confundir consumidor na hora da compra<\/p>\n<p>O Procon em S\u00e3o Paulo solicitou que a empresa Quat\u00e1 Alimentos modifique a embalagem do soro de leite que vem sendo comercializado com o nome de Bebida L\u00e1ctea Cristina. Para o \u00f3rg\u00e3o de defesa do consumidor, a embalagem do soro de leite tem apresenta\u00e7\u00e3o semelhante \u00e0 do leite, podendo induzir o comprador a erro.<\/p>\n<p>Segundo o Procon, a empresa foi notificada no in\u00edcio do m\u00eas para apresentar explica\u00e7\u00f5es sobre o problema e, agora, deve ser convocada para fazer as adequa\u00e7\u00f5es na embalagem para que o consumidor n\u00e3o adquira o soro de leite acreditando que est\u00e1 comprando leite.<\/p>\n<p>O Procon informou que a fabricante afirmou que o produto n\u00e3o \u00e9 voltado para lactentes e crian\u00e7as de primeira inf\u00e2ncia e que, em sua apresenta\u00e7\u00e3o, n\u00e3o consta direcionamento para esse grupo. No entanto, o \u00f3rg\u00e3o de defesa do consumidor destaca que a embalagem do soro de leite cont\u00e9m o desenho de uma vaquinha, o que poderia levar o cliente a adquirir o produto achando que \u00e9 voltado para este p\u00fablico.<\/p>\n<p>Ainda de acordo com o Procon, o uso desse tipo de imagem em embalagens ou r\u00f3tulos de leites fluidos, leites em p\u00f3, leites modificados e similares de origem vegetal \u00e9 vetado pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) e pela lei que regulamenta a comercializa\u00e7\u00e3o de alimentos para lactentes e crian\u00e7as de primeira inf\u00e2ncia.<\/p>\n<p>*Com informa\u00e7\u00f5es de Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apresenta\u00e7\u00e3o do produto pode confundir consumidor na hora da compra O Procon em S\u00e3o Paulo solicitou que a empresa Quat\u00e1 Alimentos modifique a embalagem do soro de leite que vem sendo comercializado com o nome de Bebida L\u00e1ctea Cristina. Para o \u00f3rg\u00e3o de defesa do consumidor, a embalagem do soro de leite tem apresenta\u00e7\u00e3o semelhante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1827","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tudo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Apresenta\u00e7\u00e3o do produto pode confundir consumidor na hora da compra O Procon em S\u00e3o Paulo solicitou que a empresa Quat\u00e1 Alimentos modifique a embalagem do soro de leite que vem sendo comercializado com o nome de Bebida L\u00e1ctea Cristina. Para o \u00f3rg\u00e3o de defesa do consumidor, a embalagem do soro de leite tem apresenta\u00e7\u00e3o semelhante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-29T11:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Procon pede que Quat\u00e1 mude embalagem de soro de leite\",\"datePublished\":\"2022-07-29T11:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/\"},\"wordCount\":269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg\",\"articleSection\":[\"Tudo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/\",\"name\":\"Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg\",\"datePublished\":\"2022-07-29T11:10:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procon pede que Quat\u00e1 mude embalagem de soro de leite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/","og_locale":"pt_BR","og_type":"article","og_title":"Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole","og_description":"Apresenta\u00e7\u00e3o do produto pode confundir consumidor na hora da compra O Procon em S\u00e3o Paulo solicitou que a empresa Quat\u00e1 Alimentos modifique a embalagem do soro de leite que vem sendo comercializado com o nome de Bebida L\u00e1ctea Cristina. Para o \u00f3rg\u00e3o de defesa do consumidor, a embalagem do soro de leite tem apresenta\u00e7\u00e3o semelhante [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-07-29T11:10:34+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Procon pede que Quat\u00e1 mude embalagem de soro de leite","datePublished":"2022-07-29T11:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/"},"wordCount":269,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg","articleSection":["Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/","url":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/","name":"Procon pede que Quat\u00e1 mude embalagem de soro de leite - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg","datePublished":"2022-07-29T11:10:34+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-29-at-08.09.30.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/procon-pede-que-quata-mude-embalagem-de-soro-de-leite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Procon pede que Quat\u00e1 mude embalagem de soro de leite"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=1827"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1827\/revisions"}],"predecessor-version":[{"id":1830,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1827\/revisions\/1830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/1829"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=1827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=1827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=1827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}