{"id":18191,"date":"2024-06-10T18:19:56","date_gmt":"2024-06-10T21:19:56","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=18191"},"modified":"2024-06-10T18:19:56","modified_gmt":"2024-06-10T21:19:56","slug":"marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/","title":{"rendered":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1"},"content":{"rendered":"<p><em>Volume de recursos foi intermediado pelo Secret\u00e1rio Municipal de Governo e Obras, Marcello Barbosa<\/em><\/p>\n<p>2024 \u00e9 um ano marcado pelas elei\u00e7\u00f5es municipais e, por conta disso, os eleitores costumam avaliar at\u00e9 que ponto os candidatos t\u00eam condi\u00e7\u00f5es de executar as propostas que s\u00e3o lan\u00e7adas durante a campanha. Nesse sentido, o apoio concedido por deputados estaduais e federais se torna fundamental para quem quer ter sucesso nas urnas, principalmente quando o parlamentar prova, na pr\u00e1tica, que j\u00e1 \u00e9 parceiro do munic\u00edpio.<\/p>\n<p>Em Itaquaquecetuba, por exemplo, o prefeito Eduardo Boigues (PL) conta com o apoio do presidente nacional do Republicanos, o deputado federal Marcos Pereira. Parceiro do munic\u00edpio desde o in\u00edcio da gest\u00e3o (2021), Marcos Pereira destinou, por meio de emendas parlamentares, mais de R$ 17 milh\u00f5es em investimentos para a cidade somente nesses pouco mais de tr\u00eas anos.<\/p>\n<p>Em 2021, Marcos Pereira destinou R$ 750 mil em recursos para Itaqu\u00e1, sendo um recurso de bancada de R$ 300 mil para a \u00e1rea da Sa\u00fade, mais R$ 200 mil de emenda pr\u00f3pria tamb\u00e9m para a Sa\u00fade e R$ 250 mil para estrutura\u00e7\u00e3o de rede de servi\u00e7os do SUAS (Sistema \u00danico de Assist\u00eancia Social).<\/p>\n<p>2022 tamb\u00e9m foi um ano de conquistas, sendo que a somat\u00f3ria ultrapassa os R$ 4,5 milh\u00f5es: duas indica\u00e7\u00f5es de recursos do programa Alimenta Brasil, do Minist\u00e9rio da Cidadania, sendo uma no valor de R$ 4.022.000,00 e outra de R$ 200 mil; R$ 300 mil para o custeio da Sa\u00fade; al\u00e9m da doa\u00e7\u00e3o de uma motoniveladora.<\/p>\n<p>J\u00e1 em 2023, Itaqu\u00e1 obteve recorde em investimentos intermediados por Marcos Pereira: R$ 7 milh\u00f5es do Minist\u00e9rio das Cidades; R$ 3,9 milh\u00f5es do Minist\u00e9rio da Integra\u00e7\u00e3o e do Desenvolvimento Regional; R$ 960 mil do Minist\u00e9rio das Cidades; e R$ 400 mil para custeio da Sa\u00fade.<\/p>\n<p>Al\u00e9m disso, o deputado tamb\u00e9m destinou R$ 603 mil para a constru\u00e7\u00e3o de uma Areninha no bairro Jardim Altos de Itaqu\u00e1. O equipamento foi inaugurado em 15 de abril e contou com a participa\u00e7\u00e3o de Marcos Pereira. \u00c0 \u00e9poca, ele refor\u00e7ou seu apoio ao munic\u00edpio: \u201c\u00a0\u201c\u00c9 a necessidade de trazer melhorias na qualidade de vida das pessoas, os agentes p\u00fablicos que aqui est\u00e3o, com o prefeito Eduardo, como o secret\u00e1rio Marcello Barbosa, [de Governo e Obras], que \u00e9 o presidente do meu partido na cidade e coordenador na regi\u00e3o. Esse \u00e9 o principal v\u00ednculo, al\u00e9m do nosso compromisso com o bem p\u00fablico\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Articula\u00e7\u00e3o pol\u00edtica<\/strong><\/p>\n<p>Para reconquistar a credibilidade de Itaquaquecetuba junto a deputados e outras esferas de governo, o prefeito Eduardo Boigues montou uma equipe de governo que o auxilia na interlocu\u00e7\u00e3o com as lideran\u00e7as pol\u00edticas. O secret\u00e1rio municipal de Obras e de Governo, Marcello Barbosa, \u00e9 um desses \u201cauxiliares\u201d.<\/p>\n<p>Presidente do Diret\u00f3rio Municipal do Republicanos de Itaquaquecetuba desde 2020, ele tem acesso direto a Marcos Pereira e, portanto, foi quem aproximou a cidade do gabinete do deputado federal. O resultado \u00e9 concreto: R$ 17 milh\u00f5es em conquistas para Itaqu\u00e1.<\/p>\n<p>\u201cEssa \u00e9 uma constru\u00e7\u00e3o que a gente faz desde o primeiro dia de governo. Eu assumi a Presid\u00eancia do partido em 2020, ainda fora da prefeitura, e quando assumimos a Secretaria de Governo, nos aproximamos do deputado Marcos Pereira para traze-lo para mais perto da cidade, com o apoio do prefeito Eduardo Boigues, para que a gente pudesse investir cada vez mais\u201d, discorreu Barbosa sobre a rela\u00e7\u00e3o com o deputado.<\/p>\n<p><strong>Alto Tiet\u00ea<\/strong><\/p>\n<p>Devido \u00e0 atua\u00e7\u00e3o expressiva em Itaqu\u00e1, Marcello Barbosa ampliou seu trabalho de coordena\u00e7\u00e3o do Republicanos no Alto Tiet\u00ea. Na \u00faltima janela partid\u00e1ria, por exemplo, filiou tr\u00eas vereadores de Itaquaquecetuba ao partido (embora a sigla partid\u00e1ria n\u00e3o tenha eleito ningu\u00e9m em 2020) e na regi\u00e3o houve um salto de 08 parlamentares para 16 al\u00e9m da constitui\u00e7\u00e3o de Comiss\u00f5es provis\u00f3rias que consolidaram boas chapas para a elei\u00e7\u00e3o de vereadores.<\/p>\n<p>De acordo com ele, \u00e9 esse modelo de trabalho que o Republicanos quer levar a todas as cidades da regi\u00e3o: \u201cA nossa ideia \u00e9 que a sigla n\u00e3o tenha um papel somente eleitoral, que o Republicanos apare\u00e7a apenas na elei\u00e7\u00e3o; a nossa sigla quer contribuir com a popula\u00e7\u00e3o\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volume de recursos foi intermediado pelo Secret\u00e1rio Municipal de Governo e Obras, Marcello Barbosa 2024 \u00e9 um ano marcado pelas elei\u00e7\u00f5es municipais e, por conta disso, os eleitores costumam avaliar at\u00e9 que ponto os candidatos t\u00eam condi\u00e7\u00f5es de executar as propostas que s\u00e3o lan\u00e7adas durante a campanha. Nesse sentido, o apoio concedido por deputados estaduais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-18191","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-itaqua"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Volume de recursos foi intermediado pelo Secret\u00e1rio Municipal de Governo e Obras, Marcello Barbosa 2024 \u00e9 um ano marcado pelas elei\u00e7\u00f5es municipais e, por conta disso, os eleitores costumam avaliar at\u00e9 que ponto os candidatos t\u00eam condi\u00e7\u00f5es de executar as propostas que s\u00e3o lan\u00e7adas durante a campanha. Nesse sentido, o apoio concedido por deputados estaduais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T21:19:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"1016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1\",\"datePublished\":\"2024-06-10T21:19:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/\"},\"wordCount\":720,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg\",\"articleSection\":[\"Itaqu\u00e1\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/\",\"name\":\"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg\",\"datePublished\":\"2024-06-10T21:19:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg\",\"width\":630,\"height\":1016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/","og_locale":"pt_BR","og_type":"article","og_title":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole","og_description":"Volume de recursos foi intermediado pelo Secret\u00e1rio Municipal de Governo e Obras, Marcello Barbosa 2024 \u00e9 um ano marcado pelas elei\u00e7\u00f5es municipais e, por conta disso, os eleitores costumam avaliar at\u00e9 que ponto os candidatos t\u00eam condi\u00e7\u00f5es de executar as propostas que s\u00e3o lan\u00e7adas durante a campanha. Nesse sentido, o apoio concedido por deputados estaduais [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2024-06-10T21:19:56+00:00","og_image":[{"width":630,"height":1016,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1","datePublished":"2024-06-10T21:19:56+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/"},"wordCount":720,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg","articleSection":["Itaqu\u00e1"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/","url":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/","name":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1 - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg","datePublished":"2024-06-10T21:19:56+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/06\/dee3ba5f-dfff-423b-8b30-2e40877f8d03.jpeg","width":630,"height":1016},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/marcos-pereira-ja-destinou-mais-de-r-17-milhoes-para-itaqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Marcos Pereira j\u00e1 destinou mais de R$ 17 milh\u00f5es para Itaqu\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/18191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=18191"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/18191\/revisions"}],"predecessor-version":[{"id":18193,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/18191\/revisions\/18193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/18192"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=18191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=18191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=18191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}