{"id":17667,"date":"2024-05-28T19:25:04","date_gmt":"2024-05-28T22:25:04","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=17667"},"modified":"2024-05-28T19:53:34","modified_gmt":"2024-05-28T22:53:34","slug":"__trashed-3","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/","title":{"rendered":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-17667","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-tudo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-28T22:25:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T22:53:34+00:00\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil\",\"datePublished\":\"2024-05-28T22:25:04+00:00\",\"dateModified\":\"2024-05-28T22:53:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/\"},\"wordCount\":137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"articleSection\":[\"Tudo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/\",\"name\":\"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"datePublished\":\"2024-05-28T22:25:04+00:00\",\"dateModified\":\"2024-05-28T22:53:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/__trashed-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole","og_url":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2024-05-28T22:25:04+00:00","article_modified_time":"2024-05-28T22:53:34+00:00","author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil","datePublished":"2024-05-28T22:25:04+00:00","dateModified":"2024-05-28T22:53:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/"},"wordCount":137,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"articleSection":["Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/__trashed-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/","url":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/","name":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"datePublished":"2024-05-28T22:25:04+00:00","dateModified":"2024-05-28T22:53:34+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/__trashed-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/__trashed-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Tony Ramos passa por cirurgia no c\u00e9rebro; estado de sa\u00fade \u00e9 est\u00e1vel Ator foi internado para tratar um sangramento intracraniano O ator Tony Ramos, de 75 anos, foi internado nesta quinta-feira (16) no Hospital Samaritano Botafogo, no Rio de Janeiro, para tratar um sangramento no c\u00e9rebro. De acordo com boletim m\u00e9dico divulgado pelo hospital, o ator foi submetido a uma cirurgia de drenagem de hematoma subdural. O estado de sa\u00fade \u00e9 est\u00e1vel. Novo boletim m\u00e9dico deve ser divulgado na tarde desta sexta-feira (17). O Teatro da Pontif\u00edcia Universidade Cat\u00f3lica de S\u00e3o Paulo (Tuca) informou, nas redes sociais, o cancelamento das sess\u00f5es \u2013 dos dias 17,18 e 19 de maio \u2013 da pe\u00e7a \u201cO que s\u00f3 sabemos juntos\u201d, encenada por Tony Ramos e a atriz Denise Fraga. *Com informa\u00e7\u00f5es de Ag\u00eancia Brasil"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/17667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=17667"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/17667\/revisions"}],"predecessor-version":[{"id":17900,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/17667\/revisions\/17900"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=17667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=17667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=17667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}