{"id":15669,"date":"2024-02-19T17:36:16","date_gmt":"2024-02-19T20:36:16","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=15669"},"modified":"2024-02-19T17:36:16","modified_gmt":"2024-02-19T20:36:16","slug":"em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/","title":{"rendered":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea"},"content":{"rendered":"<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Peso maior \u00e9 explicado pela alta no pre\u00e7o dos alimentos<\/h3>\n<p>Em janeiro, a infla\u00e7\u00e3o pesou mais no bolso das fam\u00edlias de baixa renda do que no or\u00e7amento das fam\u00edlias de rendas m\u00e9dia e alta. A constata\u00e7\u00e3o faz parte do Indicador de Infla\u00e7\u00e3o por Faixa de Renda, divulgado nesta segunda-feira (19) pelo Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1581686&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1581686&amp;o=node\" \/><\/p>\n<p>De acordo com o levantamento, enquanto a infla\u00e7\u00e3o oficial do pa\u00eds &#8211;\u00a0\u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA) &#8211;\u00a0\u00a0calculado pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) foi de 0,42% em janeiro, a infla\u00e7\u00e3o para fam\u00edlias de renda muito baixa (renda mensal domiciliar de at\u00e9 R$ 2.105,99) ficou em 0,66%.<\/p>\n<p>Os grupos familiares de renda baixa (entre R$ 2.105,99 e R$ 3.158,99) e m\u00e9dia-baixa (de R$ 3.158,99 e R$ 5.264,99) tamb\u00e9m sentiram no bolso uma infla\u00e7\u00e3o maior que a m\u00e9dia, 0,59% e 0,49%, respectivamente.<\/p>\n<p>Por outro lado, lares de renda m\u00e9dia (de R$ 5.264,98 e R$ 10.529,96), m\u00e9dia-alta (de R$ 10.529,96 e R$ 21.059,92) e, especialmente, alta (acima de R$ 21.059,92) sentiram impactos de aumentos de pre\u00e7os abaixo da infla\u00e7\u00e3o oficial, 0,37%, 0,38% e 0,04%, respectivamente.<\/p>\n<h2>Alimentos<\/h2>\n<p>De acordo com o Ipea, o peso maior do custo de vida para os lares mais pobres \u00e9 explicado pela alta nos pre\u00e7os dos alimentos. Isso acontece porque\u00a0a parcela do or\u00e7amento gasta com a compra de alimentos \u00e9 bem maior para as fam\u00edlias mais pobres, em rela\u00e7\u00e3o \u00e0 observada no segmento de renda mais alta.<\/p>\n<p>\u201cEm janeiro, o principal foco inflacion\u00e1rio para as classes de rendas mais baixas veio do grupo alimentos e bebidas, refletindo a alta dos pre\u00e7os dos alimentos no domic\u00edlio, especialmente dos cereais (6,8%), dos tub\u00e9rculos (11,1%), das frutas (5,1%) e dos \u00f3leos e gorduras (2,1%)\u201d, explica a pesquisadora do Ipea Maria Andreia Parente Lameiras.<\/p>\n<p>No m\u00eas de janeiro, o comportamento no pre\u00e7o dos alimentos representou um peso de 0,44 pontos percentuais (p.p.) na infla\u00e7\u00e3o das fam\u00edlias de renda muito baixa. J\u00e1 para os grupamentos familiares de renda mais alta, o peso foi de 0,14 p.p.<\/p>\n<p>Os lares mais abastados contaram com outra contribui\u00e7\u00e3o para sentirem menos os efeitos da infla\u00e7\u00e3o: a queda de 15,2% dos pre\u00e7os das passagens a\u00e9reas e de 10,2% das tarifas de transporte por aplicativo.<\/p>\n<h2>Invers\u00e3o em 12 meses<\/h2>\n<p>Os resultados de janeiro ficaram na contram\u00e3o do acumulado nos \u00faltimos 12 meses. No per\u00edodo, foram as fam\u00edlias de rendas m\u00e9dia (4,65%), m\u00e9dia-alta (4,93%) e alta (5,67%) que sentiram infla\u00e7\u00e3o maior que a m\u00e9dia nacional (4,51%).<\/p>\n<p>Por outro lado, domic\u00edlios de renda muito baixa (3,47%), baixa (3,84%) e m\u00e9dia-baixa (4,24%) sentiram um peso menor que o IPCA no or\u00e7amento.<\/p>\n<p>O Ipea explica que as maiores press\u00f5es inflacion\u00e1rias nos \u00faltimos doze meses foram nos grupos transportes, sa\u00fade e cuidados pessoais e habita\u00e7\u00e3o, impactados pelos reajustes de 25,5% das passagens a\u00e9reas, de 10,8% da gasolina, de 6,2% dos produtos farmac\u00eauticos, de 5,6% dos artigos de higiene, de 11% dos planos de sa\u00fade e de 8,6% da energia el\u00e9trica.<\/p>\n<p>*Com informa\u00e7\u00f5es de Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peso maior \u00e9 explicado pela alta no pre\u00e7o dos alimentos Em janeiro, a infla\u00e7\u00e3o pesou mais no bolso das fam\u00edlias de baixa renda do que no or\u00e7amento das fam\u00edlias de rendas m\u00e9dia e alta. A constata\u00e7\u00e3o faz parte do Indicador de Infla\u00e7\u00e3o por Faixa de Renda, divulgado nesta segunda-feira (19) pelo Instituto de Pesquisa Econ\u00f4mica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-15669","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tudo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Peso maior \u00e9 explicado pela alta no pre\u00e7o dos alimentos Em janeiro, a infla\u00e7\u00e3o pesou mais no bolso das fam\u00edlias de baixa renda do que no or\u00e7amento das fam\u00edlias de rendas m\u00e9dia e alta. A constata\u00e7\u00e3o faz parte do Indicador de Infla\u00e7\u00e3o por Faixa de Renda, divulgado nesta segunda-feira (19) pelo Instituto de Pesquisa Econ\u00f4mica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T20:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea\",\"datePublished\":\"2024-02-19T20:36:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/\"},\"wordCount\":524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/supermercado_economia_20220729_0889.webp\",\"articleSection\":[\"Tudo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/\",\"name\":\"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/supermercado_economia_20220729_0889.webp\",\"datePublished\":\"2024-02-19T20:36:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/supermercado_economia_20220729_0889.webp\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/supermercado_economia_20220729_0889.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/","og_locale":"pt_BR","og_type":"article","og_title":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole","og_description":"Peso maior \u00e9 explicado pela alta no pre\u00e7o dos alimentos Em janeiro, a infla\u00e7\u00e3o pesou mais no bolso das fam\u00edlias de baixa renda do que no or\u00e7amento das fam\u00edlias de rendas m\u00e9dia e alta. A constata\u00e7\u00e3o faz parte do Indicador de Infla\u00e7\u00e3o por Faixa de Renda, divulgado nesta segunda-feira (19) pelo Instituto de Pesquisa Econ\u00f4mica [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2024-02-19T20:36:16+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp","type":"image\/webp"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea","datePublished":"2024-02-19T20:36:16+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/"},"wordCount":524,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp","articleSection":["Tudo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/","url":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/","name":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp","datePublished":"2024-02-19T20:36:16+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2024\/02\/supermercado_economia_20220729_0889.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/em-janeiro-inflacao-pesou-mais-para-a-baixa-renda-diz-ipea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Em janeiro, infla\u00e7\u00e3o pesou mais para a baixa renda, diz Ipea"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/15669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=15669"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/15669\/revisions"}],"predecessor-version":[{"id":15671,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/15669\/revisions\/15671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/15670"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=15669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=15669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=15669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}