{"id":1453,"date":"2022-07-14T11:13:38","date_gmt":"2022-07-14T14:13:38","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=1453"},"modified":"2022-07-14T11:13:38","modified_gmt":"2022-07-14T14:13:38","slug":"raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/","title":{"rendered":"Raul &#8211; O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock."},"content":{"rendered":"<p>Para celebrar o dia mundial do Rock, o JM Metr\u00f3pole traz pra voc\u00ea, leitor, a cr\u00edtica do document\u00e1rio sobre o Raulzito, chamado de \u201cRAUL \u2013 O IN\u00cdCIO, O FIM E O MEIO\u201d, Com lan\u00e7amento em 2012, o filme do astro brasileiro do rock n roll, assim como o legado de Rauzito, \u00e9 sempre atual.<\/p>\n<p>O longa foi dirigido por Walter Carvalho, profissional que j\u00e1 tinha grandes trabalhos no curr\u00edculo, como a dire\u00e7\u00e3o da elogiada cinebiografia do Cazuza (2004) ou a fotografia de outros bem-sucedidos longas, como Carandiru, Amarelo Manga, Abril Despeda\u00e7ado, Lavoura Arcaica, Madame Sat\u00e3, Central do Brasil, entre outros.<\/p>\n<p>Vale muito \u00e0 pena assistir ao filme de mais de duas horas e ver a transforma\u00e7\u00e3o de Rauzito em Raul Seixas, mergulhar no mundo desse \u00edcone da m\u00fasica brasileira.<\/p>\n<p>O filme conta com depoimentos importantes, como de ex mulheres de Raul, filhos e tamb\u00e9m do amigo e parceiro de produ\u00e7\u00e3o musical, o famoso escritor, Paulo Coelho.<\/p>\n<p>Em certa cena do filme, entrevistados dizem que Raul incorporou o personagem \u201cmaluco beleza\u201d, que era, em certa medida, teatral, e que ele n\u00e3o se permitia ser, para a maioria das pessoas, o cara carinhoso e comum que podia ter sido.<\/p>\n<p>Na hist\u00f3ria \u00e9 poss\u00edvel observar como as drogas e o \u00e1lcool foram respons\u00e1veis pela destrui\u00e7\u00e3o de alguns aspectos da vida do astro.<\/p>\n<p>A carreira de Raul Seixas foi relativamente curta (de 1968 a 1989, sendo que em 1968 ele ainda era \u201cRaulzito e seus panteras\u201d, s\u00f3 se transformando em Raul Seixas com o primeiro solo, de 1971) e que em seus \u00faltimos anos de vida passou por ostracismos longe de palcos e recusas de gravadores.<\/p>\n<p>No final da carreira e da vida, Raul era persona non grata e seu nome era maldito nos corredores da m\u00eddia, fazendo com que ele passasse por muitas dificuldades para sobreviver.<\/p>\n<p>Neste cen\u00e1rio, que aparece na trama, Marcelo Nova, roqueiro com quem gravou o derradeiro disco e fez os 50 \u00faltimos shows antes de pegar o trem das sete. A abordagem de Marcelo sobre a trajet\u00f3ria e sua parceria com Raul Seixas, \u00e9 emocionante e leva o expectador a profundas reflex\u00f5es.<\/p>\n<p>O longa tamb\u00e9m conta com a participa\u00e7\u00e3o de amigos de inf\u00e2ncia do Raul, lembrando e dramatizando os primeiros dias do clube de f\u00e3s do Elvis, do qual Raulzito fez parte.<br \/>\nVoc\u00ea ficar\u00e1 surpreso com o ritmo da hist\u00f3ria e a quantidade de amores e traumas e recome\u00e7os pelos quais passou nosso mais querido carimbador maluco.<\/p>\n<p>O filme \u00e9 uma boa oportunidade para fugir do banal \u201ctoca Raul\u201d \u00e9 se aprofundar na biografia desse cara, permitindo-se descobrir que ele foi mais genial do que parece, recebendo elogio de pessoas como Caetano Veloso, Nelson Mota, Tom Z\u00e9, entre outros\u2026 t\u00e1! Ok! Tem elogio at\u00e9 do Pedro Bial.<\/p>\n<p>Prepare a pipoca. O filme est\u00e1 dispon\u00edvel na plataforma Netflix e \u00e9 garantia de uma agrad\u00e1vel e instrutiva viajem na hist\u00f3ria da m\u00fasica brasileira e do para muitos, maior astro brasileiro do rock.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para celebrar o dia mundial do Rock, o JM Metr\u00f3pole traz pra voc\u00ea, leitor, a cr\u00edtica do document\u00e1rio sobre o Raulzito, chamado de \u201cRAUL \u2013 O IN\u00cdCIO, O FIM E O MEIO\u201d, Com lan\u00e7amento em 2012, o filme do astro brasileiro do rock n roll, assim como o legado de Rauzito, \u00e9 sempre atual. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"post-1453","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cultura"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Para celebrar o dia mundial do Rock, o JM Metr\u00f3pole traz pra voc\u00ea, leitor, a cr\u00edtica do document\u00e1rio sobre o Raulzito, chamado de \u201cRAUL \u2013 O IN\u00cdCIO, O FIM E O MEIO\u201d, Com lan\u00e7amento em 2012, o filme do astro brasileiro do rock n roll, assim como o legado de Rauzito, \u00e9 sempre atual. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T14:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Raul &#8211; O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock.\",\"datePublished\":\"2022-07-14T14:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/\",\"name\":\"Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg\",\"datePublished\":\"2022-07-14T14:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg\",\"width\":1134,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raul &#8211; O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/","og_locale":"pt_BR","og_type":"article","og_title":"Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole","og_description":"Para celebrar o dia mundial do Rock, o JM Metr\u00f3pole traz pra voc\u00ea, leitor, a cr\u00edtica do document\u00e1rio sobre o Raulzito, chamado de \u201cRAUL \u2013 O IN\u00cdCIO, O FIM E O MEIO\u201d, Com lan\u00e7amento em 2012, o filme do astro brasileiro do rock n roll, assim como o legado de Rauzito, \u00e9 sempre atual. O [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-07-14T14:13:38+00:00","og_image":[{"width":1134,"height":1600,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Raul &#8211; O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock.","datePublished":"2022-07-14T14:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg","articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/","url":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/","name":"Raul - O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock. - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg","datePublished":"2022-07-14T14:13:38+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-07-14-at-09.00.13.jpeg","width":1134,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/raul-o-inicio-o-fim-e-meio-e-uma-sensacional-viagem-pela-historia-so-astro-brasileiro-do-rock\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Raul &#8211; O in\u00edcio, o fim e meio \u00e9 uma sensacional viagem pela hist\u00f3ria s\u00f3 astro brasileiro do rock."}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":1455,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1453\/revisions\/1455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/1454"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}