{"id":13383,"date":"2023-10-13T17:16:24","date_gmt":"2023-10-13T20:16:24","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=13383"},"modified":"2023-10-13T17:16:24","modified_gmt":"2023-10-13T20:16:24","slug":"gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/","title":{"rendered":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes"},"content":{"rendered":"<p>Romu fez a abordagem do ve\u00edculo ocupado por dois menores de idade no Jardim Varan; outros dois carros foram localizados por agentes da For\u00e7a Patrulha e do Canil<\/p>\n<p>Um patrulhamento realizado pela Ronda Ostensiva Municipal (Romu) da Guarda Civil Municipal (GCM) de Suzano realizado na \u00faltima sexta-feira (06\/10) na rua Joana Pereira da Silva, no Jardim Varan, resultou na localiza\u00e7\u00e3o de uma motocicleta irregular, sem placa, com poss\u00edvel queixa de roubo ou furto.<\/p>\n<p>A ocorr\u00eancia se deu por volta das 22h30 quando os agentes perceberam que o condutor do ve\u00edculo acelerou ao notar a presen\u00e7a da GCM. A atitude tomada pelo motociclista, na companhia do garupa, levantou suspeitas e um breve acompanhamento teve in\u00edcio at\u00e9 a rua onde ocorreu a abordagem.<\/p>\n<p>Durante averigua\u00e7\u00e3o, al\u00e9m da placa, a motocicleta n\u00e3o apresentava n\u00fameros de chassi nem de motor, prejudicando a identifica\u00e7\u00e3o. Em raz\u00e3o dessa inconsist\u00eancia, a moto foi levada para a Delegacia Central de Pol\u00edcia. Os ocupantes, ambos menores, tamb\u00e9m foram levados \u00e0 Pol\u00edcia Civil e devolvidos aos respons\u00e1veis.<\/p>\n<p>Um dia depois, no s\u00e1bado (07\/10), \u00e0s 7h35, pela estrada do Okabe, no Jardim Casa Branca, um Chevrolet Corsa, de cor azul, foi encontrado em estado de abandono por uma equipe da For\u00e7a Patrulha. O carro havia sido furtado na madrugada do mesmo dia. O autom\u00f3vel estava sem bateria, com algumas rodas subtra\u00eddas e com cap\u00f4 e portas abertas. O carro foi levado para a Delegacia Central.<\/p>\n<p>J\u00e1 na \u00faltima segunda-feira (09\/10), por volta das 20 horas, um Fiat Uno, envelopado com adesivos de uma empresa, foi localizado pela Romu entre a rua Lu\u00eds Afonso e a estrada dos Fernandes, tamb\u00e9m no Jardim Casa Branca. Mais cedo, o carro havia sido roubado na rua Isabel Castanheda Mayer, distante cerca de um quil\u00f4metro do local onde o Uno havia sido encontrado. O autom\u00f3vel foi devolvido aos propriet\u00e1rios.<\/p>\n<p>Dias anteriores<\/p>\n<p>Em 30 de setembro (s\u00e1bado), no Jardim Varan, agentes do Canil suspeitaram de um ve\u00edculo Fiat Fastback, preto, estacionado na rua Maria Dias dos Reis. Rapidamente foi realizada uma consulta, que constatou que o carro \u00e9 produto de roubo na madrugada do mesmo dia. O caso tamb\u00e9m foi levado para a Delegacia Central.<\/p>\n<p>Por fim, em 20 de setembro (quarta-feira), um Ford Ka, prata, com queixa de furto no dia anterior foi encontrado na estrada do Matsuzaki, na Vila Barros, pela For\u00e7a Patrulha. Na ocasi\u00e3o, os guardas notaram que o carro tinha sinais de colis\u00e3o contra uma \u00e1rvore. O autom\u00f3vel foi guinchado at\u00e9 a Delegacia Central e depois devolvido ao propriet\u00e1rio.<\/p>\n<p>O secret\u00e1rio de Seguran\u00e7a Cidad\u00e3 de Suzano, Afr\u00e2nio Evaristo da Silva, salientou que o trabalho de ronda \u00e9 imprescind\u00edvel para ajudar na elucida\u00e7\u00e3o de crimes. \u201cUma das a\u00e7\u00f5es cruciais \u00e9 promover o patrulhamento nas ruas. Al\u00e9m de elevar a sensa\u00e7\u00e3o de seguran\u00e7a, conseguimos localizar ve\u00edculos que foram alvo de roubo ou furto e que muitas vezes n\u00e3o s\u00e3o vistos pela popula\u00e7\u00e3o para gerar den\u00fancias, por isso manter nosso pessoal na rua \u00e9 motivo de mais tranquilidade para todos\u201d, definiu.<\/p>\n<p>Cr\u00e9dito das fotos: Divulga\u00e7\u00e3o\/Secop Suzano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Romu fez a abordagem do ve\u00edculo ocupado por dois menores de idade no Jardim Varan; outros dois carros foram localizados por agentes da For\u00e7a Patrulha e do Canil Um patrulhamento realizado pela Ronda Ostensiva Municipal (Romu) da Guarda Civil Municipal (GCM) de Suzano realizado na \u00faltima sexta-feira (06\/10) na rua Joana Pereira da Silva, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":{"0":"post-13383","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-suzano"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Romu fez a abordagem do ve\u00edculo ocupado por dois menores de idade no Jardim Varan; outros dois carros foram localizados por agentes da For\u00e7a Patrulha e do Canil Um patrulhamento realizado pela Ronda Ostensiva Municipal (Romu) da Guarda Civil Municipal (GCM) de Suzano realizado na \u00faltima sexta-feira (06\/10) na rua Joana Pereira da Silva, no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T20:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes\",\"datePublished\":\"2023-10-13T20:16:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/\"},\"wordCount\":558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg\",\"articleSection\":[\"Suzano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/\",\"name\":\"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg\",\"datePublished\":\"2023-10-13T20:16:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg\",\"width\":576,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/","og_locale":"pt_BR","og_type":"article","og_title":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole","og_description":"Romu fez a abordagem do ve\u00edculo ocupado por dois menores de idade no Jardim Varan; outros dois carros foram localizados por agentes da For\u00e7a Patrulha e do Canil Um patrulhamento realizado pela Ronda Ostensiva Municipal (Romu) da Guarda Civil Municipal (GCM) de Suzano realizado na \u00faltima sexta-feira (06\/10) na rua Joana Pereira da Silva, no [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2023-10-13T20:16:24+00:00","og_image":[{"width":576,"height":576,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes","datePublished":"2023-10-13T20:16:24+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/"},"wordCount":558,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg","articleSection":["Suzano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/","url":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/","name":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg","datePublished":"2023-10-13T20:16:24+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-13-at-09.00.22.jpeg","width":576,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/gcm-apreende-moto-sem-placa-e-sem-numeros-de-motor-e-de-chassi-com-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"GCM apreende moto sem placa e sem n\u00fameros de motor e de chassi com adolescentes"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=13383"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13383\/revisions"}],"predecessor-version":[{"id":13385,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13383\/revisions\/13385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/13384"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=13383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=13383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=13383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}