{"id":13245,"date":"2023-10-06T15:20:39","date_gmt":"2023-10-06T18:20:39","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=13245"},"modified":"2023-10-06T15:20:39","modified_gmt":"2023-10-06T18:20:39","slug":"provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/","title":{"rendered":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP"},"content":{"rendered":"<p>Governo de S\u00e3o Paulo oferece mais de 15 mil vagas em 2024; o Prov\u00e3o acontece entre os dias 28 de novembro e 1\u00b0 de dezembro<\/p>\n<p>O Governo de S\u00e3o Paulo anunciou neste ano o Prov\u00e3o Paulista Seriado, avalia\u00e7\u00e3o da Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (<a href=\"https:\/\/www.educacao.sp.gov.br\/institucional\/a-secretaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Seduc-SP<\/a>) que oferece mais uma chance para alunos da rede p\u00fablica ingressarem nas institui\u00e7\u00f5es estaduais paulistas de ensino superior em 2024. No total, ser\u00e3o 15.369 vagas.<\/p>\n<p>A Educa\u00e7\u00e3o de SP organizou as principais informa\u00e7\u00f5es sobre a aplica\u00e7\u00e3o do Prov\u00e3o, que acontece entre os dias 28 de novembro e 1\u00ba de dezembro. Veja a seguir.<\/p>\n<p><strong>Saiba tudo sobre o Prov\u00e3o Paulista Seriado:<\/strong><\/p>\n<p>\u25cf Alunos matriculados nas tr\u00eas s\u00e9ries do Ensino M\u00e9dio regular nas redes p\u00fablicas do Estado de S\u00e3o Paulo e em todo o pa\u00eds podem participar do Prov\u00e3o Paulista Seriado;<\/p>\n<p>\u25cf 1,1 milh\u00e3o de estudantes das 1\u00aa, 2\u00aa e 3\u00aa s\u00e9ries do Ensino M\u00e9dio matriculados nas escolas estaduais de S\u00e3o Paulo j\u00e1 est\u00e3o automaticamente inscritos no Prov\u00e3o Paulista. Ou seja, se voc\u00ea \u00e9 aluno, basta comparecer \u00e0 sua escola no dia da aplica\u00e7\u00e3o;<\/p>\n<p>\u25cf Atualmente, na rede estadual de SP s\u00e3o 435,3 mil alunos matriculados na 1\u00aa s\u00e9rie, 395,9 na 2\u00aa s\u00e9rie e 356,2 mil na 3\u00aa s\u00e9rie;<\/p>\n<p>\u25cf As 15.369 vagas s\u00e3o distribu\u00eddas nas seguintes universidades: Universidade de S\u00e3o Paulo (<a href=\"https:\/\/www5.usp.br\/institucional\/a-usp\/\" target=\"_blank\" rel=\"noopener noreferrer\">USP<\/a>), Universidade Estadual Paulista (<a href=\"https:\/\/www2.unesp.br\/portal#!\/sobre-a-unesp\/historico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Unesp<\/a>), Universidade Estadual de Campinas (<a href=\"https:\/\/www.unicamp.br\/unicamp\/historia\" target=\"_blank\" rel=\"noopener noreferrer\">Unicamp<\/a>), Universidade Virtual do Estado de S\u00e3o Paulo (<a href=\"https:\/\/univesp.br\/institucional\" target=\"_blank\" rel=\"noopener noreferrer\">Univesp<\/a>) e nas Faculdades de Tecnologia de S\u00e3o Paulo (<a href=\"http:\/\/www.fatecsp.br\/paginas\/a_fatecsp.php\" target=\"_blank\" rel=\"noopener noreferrer\">Fatecs<\/a>);<\/p>\n<p>\u25cf S\u00e3o 1.500 para a USP, 934 para a Unesp, 325 para a Unicamp, 2.620 vagas para a Univesp e 10.000 vagas para as Fatecs;<\/p>\n<p>\u25cf Entre os cursos mais procurados em vestibulares do pa\u00eds, est\u00e3o 558 vagas para as diversas \u00e1reas da engenharia, 89 vagas para direito, 67 para medicina e 33 para psicologia;<\/p>\n<p>\u25cf A partir do dia 1\u00ba de novembro, os alunos da rede p\u00fablica estadual e todos os demais inscritos ter\u00e3o \u00e0 disposi\u00e7\u00e3o uma p\u00e1gina para escolher entre as op\u00e7\u00f5es de curso e unidade de interesse;<\/p>\n<p>\u25cf Alunos das escolas t\u00e9cnicas estaduais (<a href=\"https:\/\/www.cps.sp.gov.br\/etec\/\" target=\"_blank\" rel=\"noopener noreferrer\">Etecs<\/a>) do Centro Paula Souza tamb\u00e9m j\u00e1 est\u00e3o automaticamente inscritos nas provas, que ser\u00e3o aplicadas nas escolas de origem;<\/p>\n<p>\u25cf Estudantes de outras redes p\u00fablicas de S\u00e3o Paulo n\u00e3o administradas pela Seduc-SP e pelo Centro Paula Souza devem conferir a regra de participa\u00e7\u00e3o na Resolu\u00e7\u00e3o 43, publicada no Di\u00e1rio Oficial do Estado no dia 29 de setembro;<\/p>\n<p>\u25cf As provas acontecem em datas e hor\u00e1rios distintos para alunos de s\u00e9ries distintas, conforme Resolu\u00e7\u00e3o 43;<\/p>\n<p>\u25cf Para alunos da 3\u00aa s\u00e9rie do Ensino M\u00e9dio, as provas acontecem nos dias 28 e 29 de novembro, pela manh\u00e3. No primeiro dia de prova, ser\u00e3o aplicados os exames de linguagens e suas tecnologias e ci\u00eancias da natureza e suas tecnologias. No segundo dia, ser\u00e3o aplicadas as avalia\u00e7\u00f5es de matem\u00e1tica e suas tecnologias e ci\u00eancias humanas e sociais e suas tecnologias. A reda\u00e7\u00e3o tamb\u00e9m ser\u00e1 aplicada no segundo dia de Prov\u00e3o;<\/p>\n<p>\u25cf As provas da 2\u00aa s\u00e9rie do Ensino M\u00e9dio acontecem nos dias 30 de novembro e 1\u00ba de dezembro, no turno matutino. A ordem das provas por \u00e1reas de conhecimento ser\u00e1 a mesma;<\/p>\n<p>\u25cf As provas da 1\u00aa s\u00e9rie do Ensino M\u00e9dio est\u00e3o marcadas tamb\u00e9m para os dias 30 de novembro e 1\u00ba de dezembro, no per\u00edodo vespertino. Linguagens e suas tecnologias e ci\u00eancias da natureza e suas tecnologias estar\u00e3o na prova do dia 30 e matem\u00e1tica e suas tecnologias e ci\u00eancias humanas e sociais e suas tecnologias na prova do dia 1\u00ba;<\/p>\n<p>\u25cf Os resultados das provas s\u00e3o cumulativos. Ou seja, quem est\u00e1 em 2023 na 1\u00aa s\u00e9rie do Ensino M\u00e9dio far\u00e1 provas em 2024 e 2025 e todos os resultados ser\u00e3o contabilizados para que esse estudante seja aprovado, ou n\u00e3o, em uma das universidades do Estado;<\/p>\n<p>\u25cf Mora em outro estado? Voc\u00ea pode se inscrever at\u00e9 as 18h desta sexta-feira (6), por meio do site\u00a0<a href=\"https:\/\/provaopaulistaseriado.educacao.sp.gov.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/provaopaulistaseriado.educacao.sp.gov.br<\/a>\/;<\/p>\n<p>\u25cf Alunos de outros estados far\u00e3o as provas na capital paulista, em locais a serem divulgados em breve pela Secretaria da Educa\u00e7\u00e3o do Estado;<\/p>\n<p>\u25cf Todos os estudantes matriculados atualmente nas 1\u00aa e 2\u00aa s\u00e9ries do Ensino M\u00e9dio e que tiverem interessem em concorrer a uma vaga por meio do Prov\u00e3o Paulista precisar\u00e3o necessariamente participar da avalia\u00e7\u00e3o, uma vez que os resultados ser\u00e3o contabilizados nos anos de 2024 e 2025. Caso o estudante n\u00e3o realize a prova na 1\u00aa s\u00e9rie ou 2\u00aa s\u00e9rie, ele ser\u00e1 exclu\u00eddo do processo do Prov\u00e3o Paulista Seriado;<\/p>\n<p>\u25cf Todas as provas ser\u00e3o impressas;<\/p>\n<p>\u25cf Apesar de facilitar o ingresso nas universidades paulistas, o Prov\u00e3o Paulista Seriado n\u00e3o exclui a possibilidade de os estudantes interessados tamb\u00e9m participarem das sele\u00e7\u00f5es das quatro universidades, como a Fuvest, e das Fatecs.<\/p>\n<p>*Com informa\u00e7\u00f5es do Portal do Governo do Estado de S\u00e3o Paulo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Governo de S\u00e3o Paulo oferece mais de 15 mil vagas em 2024; o Prov\u00e3o acontece entre os dias 28 de novembro e 1\u00b0 de dezembro O Governo de S\u00e3o Paulo anunciou neste ano o Prov\u00e3o Paulista Seriado, avalia\u00e7\u00e3o da Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP) que oferece mais uma chance para alunos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":{"0":"post-13245","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacao"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Governo de S\u00e3o Paulo oferece mais de 15 mil vagas em 2024; o Prov\u00e3o acontece entre os dias 28 de novembro e 1\u00b0 de dezembro O Governo de S\u00e3o Paulo anunciou neste ano o Prov\u00e3o Paulista Seriado, avalia\u00e7\u00e3o da Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP) que oferece mais uma chance para alunos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-06T18:20:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP\",\"datePublished\":\"2023-10-06T18:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/\"},\"wordCount\":840,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/37553554364_4476a8303b_k-300x190-1.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/\",\"name\":\"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/37553554364_4476a8303b_k-300x190-1.jpg\",\"datePublished\":\"2023-10-06T18:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/37553554364_4476a8303b_k-300x190-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/37553554364_4476a8303b_k-300x190-1.jpg\",\"width\":300,\"height\":190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole","og_description":"Governo de S\u00e3o Paulo oferece mais de 15 mil vagas em 2024; o Prov\u00e3o acontece entre os dias 28 de novembro e 1\u00b0 de dezembro O Governo de S\u00e3o Paulo anunciou neste ano o Prov\u00e3o Paulista Seriado, avalia\u00e7\u00e3o da Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP) que oferece mais uma chance para alunos [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2023-10-06T18:20:39+00:00","og_image":[{"width":300,"height":190,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP","datePublished":"2023-10-06T18:20:39+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/"},"wordCount":840,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg","articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/","url":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/","name":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg","datePublished":"2023-10-06T18:20:39+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/10\/37553554364_4476a8303b_k-300x190-1.jpg","width":300,"height":190},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/provao-paulista-conheca-a-avaliacao-que-garante-vagas-nas-universidades-publicas-de-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Prov\u00e3o Paulista: conhe\u00e7a a avalia\u00e7\u00e3o que garante vagas nas universidades p\u00fablicas de SP"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=13245"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13245\/revisions"}],"predecessor-version":[{"id":13247,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/13245\/revisions\/13247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/13246"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=13245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=13245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=13245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}