{"id":1222,"date":"2022-07-02T08:47:17","date_gmt":"2022-07-02T11:47:17","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=1222"},"modified":"2022-07-02T08:47:17","modified_gmt":"2022-07-02T11:47:17","slug":"prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/","title":{"rendered":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas"},"content":{"rendered":"<p>Mesmo ap\u00f3s diversas mat\u00e9rias veiculadas na imprensa local, referente a den\u00fancias de alunos e pais sobre a falta de uniformes escolares, a prefeitura de Guarulhos ainda n\u00e3o conseguiu solucionar e sequer minimizar o sofrimento das crian\u00e7as, que em pleno inverno ainda n\u00e3o receberam uniformes escolares para a esta\u00e7\u00e3o.<\/p>\n<p>As den\u00fancias sobre o tema continuam a chegar a reda\u00e7\u00e3o do JM Metr\u00f3pole, sem que o poder publico municipal de Guarulhos atenda os pedidos e a necessidade de seus alunos e de seus pais, contribuintes no munic\u00edpio.<\/p>\n<p>&#8220;Estamos no inverno e meu filho por exemplo, n\u00e3o recebeu uma pe\u00e7a de uniforme de inverno. Recebemos depois de reclamar muito, uma bermuda e duas camisetas de manga curta, que para o inverno n\u00e3o servem pra nada&#8221;, reclamou M\u00e1rcia Tavares da Silva, moradora de Cumbica que tem um filho estudante da rede escolar municipal.<\/p>\n<p>Den\u00fancias sobre atraso na entrega de uniforme escolar aos alunos da rede escolar municipal de Guarulhos, s\u00e3o cada vez mais constantes.<\/p>\n<p>&#8220;As crian\u00e7as ficaram praticamente dois anos sem aula, com as escolas fechadas. Ser\u00e1 que nesse tempo todo, n\u00e3o deu pra prefeitura comprar os uniformes certos para o frio e o calor? \u00c9 muita falta de respeito com os pais e falta de responsabilidade com as crian\u00e7as que estudam nas escolas da prefeitura&#8221;, disse indignado Jo\u00e3o Prates da Silva, morador do Pimentas e av\u00f4 de um aluno da rede escolar municipal.<\/p>\n<p>Com a falta de uniformes, alguns professores e pais de alunos tem tentado minimizar o problema realizando entre as crian\u00e7as, troca de pe\u00e7as utilizadas em anos anteriores que n\u00e3o servem mais e assim tentam amenizar esse sofrimento e esse absurdo praticado pelo poder p\u00fablico municipal de Guarulhos.<\/p>\n<p>A solu\u00e7\u00e3o inteligente dos pais e professores adotada em algumas escolhas, \u00e9 a &#8220;caixa solid\u00e1ria&#8221;, onde os alunos e pais deixam pe\u00e7as que n\u00e3o vai utilizar e retiram as que possam ser de uso para cada crian\u00e7a. Desta forma podem se ajudar mutuamente e cumprir o papel que \u00e9 de responsabilidade da prefeitura e n\u00e3o \u00e9 cumprido adequadamente.<\/p>\n<p>O tema tem sido abordado com frequ\u00eancia por diversos segmentos da sociedade guarulhense, e os alunos da rede municipal e seus pais continuam aguardando uma solu\u00e7\u00e3o definitiva do poder p\u00fablico para o problema, mas que at\u00e9 agora aparentemente n\u00e3o tem prazo para acontecer.<\/p>\n<p>A prefeitura foi procurada por nossa reda\u00e7\u00e3o para prestar esclarecimentos sobre o tema, por\u00e9m at\u00e9 o fechamento desta edi\u00e7\u00e3o n\u00e3o nos enviou nenhuma resposta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mesmo ap\u00f3s diversas mat\u00e9rias veiculadas na imprensa local, referente a den\u00fancias de alunos e pais sobre a falta de uniformes escolares, a prefeitura de Guarulhos ainda n\u00e3o conseguiu solucionar e sequer minimizar o sofrimento das crian\u00e7as, que em pleno inverno ainda n\u00e3o receberam uniformes escolares para a esta\u00e7\u00e3o. As den\u00fancias sobre o tema continuam a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-1222","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guarulhos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"Mesmo ap\u00f3s diversas mat\u00e9rias veiculadas na imprensa local, referente a den\u00fancias de alunos e pais sobre a falta de uniformes escolares, a prefeitura de Guarulhos ainda n\u00e3o conseguiu solucionar e sequer minimizar o sofrimento das crian\u00e7as, que em pleno inverno ainda n\u00e3o receberam uniformes escolares para a esta\u00e7\u00e3o. As den\u00fancias sobre o tema continuam a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-02T11:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas\",\"datePublished\":\"2022-07-02T11:47:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg\",\"articleSection\":[\"Guarulhos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/\",\"name\":\"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg\",\"datePublished\":\"2022-07-02T11:47:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg\",\"width\":720,\"height\":318},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole","og_description":"Mesmo ap\u00f3s diversas mat\u00e9rias veiculadas na imprensa local, referente a den\u00fancias de alunos e pais sobre a falta de uniformes escolares, a prefeitura de Guarulhos ainda n\u00e3o conseguiu solucionar e sequer minimizar o sofrimento das crian\u00e7as, que em pleno inverno ainda n\u00e3o receberam uniformes escolares para a esta\u00e7\u00e3o. As den\u00fancias sobre o tema continuam a [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2022-07-02T11:47:17+00:00","og_image":[{"width":720,"height":318,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas","datePublished":"2022-07-02T11:47:17+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg","articleSection":["Guarulhos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/","url":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/","name":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg","datePublished":"2022-07-02T11:47:17+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2022\/07\/WhatsApp-Image-2022-06-30-at-16.35.42-1.jpeg","width":720,"height":318},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/prefeitura-de-guarulhos-nao-entrega-uniformes-escolares-de-inverno-e-alunos-continuam-desassistidos-e-sofrendo-com-as-baixas-temperaturas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de Guarulhos n\u00e3o entrega uniformes escolares de inverno e alunos continuam desassistidos e sofrendo com as baixas temperaturas"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"predecessor-version":[{"id":1224,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/1222\/revisions\/1224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/1223"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}