{"id":11357,"date":"2023-07-28T05:03:02","date_gmt":"2023-07-28T08:03:02","guid":{"rendered":"https:\/\/jm-metropole.com.br\/site\/?p=11357"},"modified":"2023-07-28T05:03:02","modified_gmt":"2023-07-28T08:03:02","slug":"blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas","status":"publish","type":"post","link":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/","title":{"rendered":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas"},"content":{"rendered":"<p>A Prefeitura de Guarulhos e as pol\u00edcias Militar, Civil, Rodovi\u00e1ria Estadual e Rodovi\u00e1ria Federal realizaram entre 21h de quarta-feira (26) e a meia-noite desta quinta-feira (27) uma nova edi\u00e7\u00e3o da Blitz da Lei Seca. Desta vez foram fiscalizados 598 condutores, sendo que 12 motoristas foram autuados por conta da presen\u00e7a de \u00e1lcool constatado no teste do baf\u00f4metro.<\/p>\n<p>Foram lavradas ainda 14 autua\u00e7\u00f5es por diversos motivos, como documenta\u00e7\u00e3o irregular, uso de celular ao volante, falta do uso de cinto de seguran\u00e7a, entre outros. Um ve\u00edculo foi removido ao p\u00e1tio.<\/p>\n<p>As for\u00e7as de seguran\u00e7a presentes tamb\u00e9m conduziram duas pessoas ao 1\u00b0 Distrito Policial, localizado na regi\u00e3o central, pois portavam cinco aparelhos celulares de proced\u00eancia duvidosa.<\/p>\n<p>A blitz ocorreu nas rodovias Presidente Dutra e Ayrton Senna e na estrada Presidente Juscelino Kubitschek de Oliveira. Educadores de tr\u00e2nsito que participaram da opera\u00e7\u00e3o distribu\u00edram lixos para autom\u00f3veis.<\/p>\n<p>Participaram da fiscaliza\u00e7\u00e3o agentes de tr\u00e2nsito da Secretaria de Transportes e Mobilidade Urbana e da Guarda Civil Municipal de Guarulhos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Guarulhos e as pol\u00edcias Militar, Civil, Rodovi\u00e1ria Estadual e Rodovi\u00e1ria Federal realizaram entre 21h de quarta-feira (26) e a meia-noite desta quinta-feira (27) uma nova edi\u00e7\u00e3o da Blitz da Lei Seca. Desta vez foram fiscalizados 598 condutores, sendo que 12 motoristas foram autuados por conta da presen\u00e7a de \u00e1lcool constatado no teste [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-11357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guarulhos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Guarulhos e as pol\u00edcias Militar, Civil, Rodovi\u00e1ria Estadual e Rodovi\u00e1ria Federal realizaram entre 21h de quarta-feira (26) e a meia-noite desta quinta-feira (27) uma nova edi\u00e7\u00e3o da Blitz da Lei Seca. Desta vez foram fiscalizados 598 condutores, sendo que 12 motoristas foram autuados por conta da presen\u00e7a de \u00e1lcool constatado no teste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jm.metropole\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T08:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal Metr\u00f3pole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal Metr\u00f3pole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/\"},\"author\":{\"name\":\"Jornal Metr\u00f3pole\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\"},\"headline\":\"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas\",\"datePublished\":\"2023-07-28T08:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg\",\"articleSection\":[\"Guarulhos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/\",\"name\":\"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg\",\"datePublished\":\"2023-07-28T08:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"name\":\"Jornal Metr\u00f3pole\",\"description\":\"Alto Tiet\u00ea e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#organization\",\"name\":\"Jornal Metr\u00f3pole\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/LOGO-JM-scaled.jpg\",\"width\":2560,\"height\":2498,\"caption\":\"Jornal Metr\u00f3pole\"},\"image\":{\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jm.metropole\",\"https:\\\/\\\/www.instagram.com\\\/jm.metropole\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a438c77cefcef76c8ddbe3dcc9b238fc\",\"name\":\"Jornal Metr\u00f3pole\",\"sameAs\":[\"https:\\\/\\\/jm-metropole.com.br\\\/site\"],\"url\":\"https:\\\/\\\/jm-metropole.com.br\\\/site\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/","og_locale":"pt_BR","og_type":"article","og_title":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole","og_description":"A Prefeitura de Guarulhos e as pol\u00edcias Militar, Civil, Rodovi\u00e1ria Estadual e Rodovi\u00e1ria Federal realizaram entre 21h de quarta-feira (26) e a meia-noite desta quinta-feira (27) uma nova edi\u00e7\u00e3o da Blitz da Lei Seca. Desta vez foram fiscalizados 598 condutores, sendo que 12 motoristas foram autuados por conta da presen\u00e7a de \u00e1lcool constatado no teste [&hellip;]","og_url":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/","og_site_name":"Jornal Metr\u00f3pole","article_publisher":"https:\/\/www.facebook.com\/jm.metropole","article_published_time":"2023-07-28T08:03:02+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg","type":"image\/jpeg"}],"author":"Jornal Metr\u00f3pole","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornal Metr\u00f3pole","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#article","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/"},"author":{"name":"Jornal Metr\u00f3pole","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc"},"headline":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas","datePublished":"2023-07-28T08:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg","articleSection":["Guarulhos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/","url":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/","name":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas - Jornal Metr\u00f3pole","isPartOf":{"@id":"https:\/\/jm-metropole.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#primaryimage"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#primaryimage"},"thumbnailUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg","datePublished":"2023-07-28T08:03:02+00:00","breadcrumb":{"@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#primaryimage","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-27-at-15.41.51.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/jm-metropole.com.br\/site\/blitz-da-lei-seca-fiscaliza-598-motoristas-em-guarulhos-em-tres-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jm-metropole.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Blitz da Lei Seca fiscaliza 598 motoristas em Guarulhos em tr\u00eas horas"}]},{"@type":"WebSite","@id":"https:\/\/jm-metropole.com.br\/site\/#website","url":"https:\/\/jm-metropole.com.br\/site\/","name":"Jornal Metr\u00f3pole","description":"Alto Tiet\u00ea e Regi\u00e3o","publisher":{"@id":"https:\/\/jm-metropole.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jm-metropole.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jm-metropole.com.br\/site\/#organization","name":"Jornal Metr\u00f3pole","url":"https:\/\/jm-metropole.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","contentUrl":"https:\/\/jm-metropole.com.br\/site\/wp-content\/uploads\/2026\/05\/LOGO-JM-scaled.jpg","width":2560,"height":2498,"caption":"Jornal Metr\u00f3pole"},"image":{"@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jm.metropole","https:\/\/www.instagram.com\/jm.metropole\/"]},{"@type":"Person","@id":"https:\/\/jm-metropole.com.br\/site\/#\/schema\/person\/a438c77cefcef76c8ddbe3dcc9b238fc","name":"Jornal Metr\u00f3pole","sameAs":["https:\/\/jm-metropole.com.br\/site"],"url":"https:\/\/jm-metropole.com.br\/site\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/11357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/comments?post=11357"}],"version-history":[{"count":1,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/11357\/revisions"}],"predecessor-version":[{"id":11359,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/posts\/11357\/revisions\/11359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media\/11358"}],"wp:attachment":[{"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/media?parent=11357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/categories?post=11357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jm-metropole.com.br\/site\/wp-json\/wp\/v2\/tags?post=11357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}